{"id":11041,"date":"2026-06-30T11:25:25","date_gmt":"2026-06-30T11:25:25","guid":{"rendered":"https:\/\/azuaalinstante.com\/?p=11041"},"modified":"2026-06-30T11:25:26","modified_gmt":"2026-06-30T11:25:26","slug":"la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico","status":"publish","type":"post","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/","title":{"rendered":"La \u201cconsulta\u201d del PLD otra vez en el centro del debate pol\u00edtico"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La respuesta de la JCE al requerimiento de Dom\u00ednguez Brito, ha reavivado el debate sobre si el proceso se adec\u00faa a las leyes electorales o no.<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/vertical_main_image\/uploads\/2024\/12\/15\/675ef43680637.jpeg\" alt=\"Fotograf\u00eda muestra l\u00edderes del Partido de la Liberaci\u00f3n Dominicana en conmemoraci\u00f3n del 51 aniversario de la organizaci\u00f3n.\"\/><figcaption class=\"wp-element-caption\">El PLD sigue con su idea de realizar el proceso el 18 de octubre del 2026.Victor Ram\u00edrez<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La noche del pasado jueves, la Junta Central Electoral (JCE) se\u00f1al\u00f3 que el proceso de \"consulta interna\" que pretende realizar el Partido de la Liberaci\u00f3n Dominicana (PLD), para escoger a su \"figura presidencial m\u00e1s aventajada\u201d, no cuenta con el respaldo legal de ninguna de las leyes que rigen el sistema pol\u00edtico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La respuesta de la JCE al requerimiento de Dom\u00ednguez Brito, ha reavivado el debate sobre si el proceso se adec\u00faa a las leyes electorales o no. La noche del pasado jueves, la Junta Central Electoral (JCE) se\u00f1al\u00f3 que el proceso de \"consulta interna\" que pretende realizar el Partido de la Liberaci\u00f3n Dominicana (PLD), para escoger [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-11041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La respuesta de la JCE al requerimiento de Dom\u00ednguez Brito, ha reavivado el debate sobre si el proceso se adec\u00faa a las leyes electorales o no. La noche del pasado jueves, la Junta Central Electoral (JCE) se\u00f1al\u00f3 que el proceso de &quot;consulta interna&quot; que pretende realizar el Partido de la Liberaci\u00f3n Dominicana (PLD), para escoger\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Redacci\u00f3n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"AZUA AL INSTANTE - SIEMPRE DETR\u00c1S DE LA NOTICIA!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La \u201cconsulta\u201d del PLD otra vez en el centro del debate pol\u00edtico - AZUA AL INSTANTE\" \/>\n\t\t<meta property=\"og:description\" content=\"La respuesta de la JCE al requerimiento de Dom\u00ednguez Brito, ha reavivado el debate sobre si el proceso se adec\u00faa a las leyes electorales o no. La noche del pasado jueves, la Junta Central Electoral (JCE) se\u00f1al\u00f3 que el proceso de &quot;consulta interna&quot; que pretende realizar el Partido de la Liberaci\u00f3n Dominicana (PLD), para escoger\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-06-30T11:25:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-30T11:25:26+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La \u201cconsulta\u201d del PLD otra vez en el centro del debate pol\u00edtico - AZUA AL INSTANTE\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La respuesta de la JCE al requerimiento de Dom\u00ednguez Brito, ha reavivado el debate sobre si el proceso se adec\u00faa a las leyes electorales o no. La noche del pasado jueves, la Junta Central Electoral (JCE) se\u00f1al\u00f3 que el proceso de &quot;consulta interna&quot; que pretende realizar el Partido de la Liberaci\u00f3n Dominicana (PLD), para escoger\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\\\/#blogposting\",\"name\":\"La \\u201cconsulta\\u201d del PLD otra vez en el centro del debate pol\\u00edtico - AZUA AL INSTANTE\",\"headline\":\"La \\u201cconsulta\\u201d del PLD otra vez en el centro del debate pol\\u00edtico\",\"author\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/675ef43680637.jpeg\",\"width\":800,\"height\":533},\"datePublished\":\"2026-06-30T11:25:25+00:00\",\"dateModified\":\"2026-06-30T11:25:26+00:00\",\"inLanguage\":\"es-DO\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\\\/#webpage\"},\"articleSection\":\"Pol\\u00edtica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/azuaalinstante.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/politica\\\/#listItem\",\"name\":\"Pol\\u00edtica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/politica\\\/#listItem\",\"position\":2,\"name\":\"Pol\\u00edtica\",\"item\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/politica\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\\\/#listItem\",\"name\":\"La \\u201cconsulta\\u201d del PLD otra vez en el centro del debate pol\\u00edtico\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\\\/#listItem\",\"position\":3,\"name\":\"La \\u201cconsulta\\u201d del PLD otra vez en el centro del debate pol\\u00edtico\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/politica\\\/#listItem\",\"name\":\"Pol\\u00edtica\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\",\"name\":\"AZUA AL INSTANTE\",\"description\":\"SIEMPRE DETR\\u00c1S DE LA NOTICIA!\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/\",\"name\":\"Redacci\\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d68b136e956cb2c839632b9025c3df5f0812f547e1ff3ca13ce11a5b13bf209c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Redacci\\u00f3n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\\\/#webpage\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\\\/\",\"name\":\"La \\u201cconsulta\\u201d del PLD otra vez en el centro del debate pol\\u00edtico - AZUA AL INSTANTE\",\"description\":\"La respuesta de la JCE al requerimiento de Dom\\u00ednguez Brito, ha reavivado el debate sobre si el proceso se adec\\u00faa a las leyes electorales o no. La noche del pasado jueves, la Junta Central Electoral (JCE) se\\u00f1al\\u00f3 que el proceso de \\\"consulta interna\\\" que pretende realizar el Partido de la Liberaci\\u00f3n Dominicana (PLD), para escoger\",\"inLanguage\":\"es-DO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/675ef43680637.jpeg\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\\\/#mainImage\"},\"datePublished\":\"2026-06-30T11:25:25+00:00\",\"dateModified\":\"2026-06-30T11:25:26+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#website\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/\",\"name\":\"AZUA AL INSTANTE\",\"description\":\"SIEMPRE DETR\\u00c1S DE LA NOTICIA!\",\"inLanguage\":\"es-DO\",\"publisher\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La \u201cconsulta\u201d del PLD otra vez en el centro del debate pol\u00edtico - AZUA AL INSTANTE","description":"La respuesta de la JCE al requerimiento de Dom\u00ednguez Brito, ha reavivado el debate sobre si el proceso se adec\u00faa a las leyes electorales o no. La noche del pasado jueves, la Junta Central Electoral (JCE) se\u00f1al\u00f3 que el proceso de \"consulta interna\" que pretende realizar el Partido de la Liberaci\u00f3n Dominicana (PLD), para escoger","canonical_url":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/#blogposting","name":"La \u201cconsulta\u201d del PLD otra vez en el centro del debate pol\u00edtico - AZUA AL INSTANTE","headline":"La \u201cconsulta\u201d del PLD otra vez en el centro del debate pol\u00edtico","author":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"publisher":{"@id":"https:\/\/azuaalinstante.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/azuaalinstante.com\/wp-content\/uploads\/2026\/06\/675ef43680637.jpeg","width":800,"height":533},"datePublished":"2026-06-30T11:25:25+00:00","dateModified":"2026-06-30T11:25:26+00:00","inLanguage":"es-DO","mainEntityOfPage":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/#webpage"},"isPartOf":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/#webpage"},"articleSection":"Pol\u00edtica"},{"@type":"BreadcrumbList","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com#listItem","position":1,"name":"Home","item":"https:\/\/azuaalinstante.com","nextItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/politica\/#listItem","name":"Pol\u00edtica"}},{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/politica\/#listItem","position":2,"name":"Pol\u00edtica","item":"https:\/\/azuaalinstante.com\/index.php\/category\/politica\/","nextItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/#listItem","name":"La \u201cconsulta\u201d del PLD otra vez en el centro del debate pol\u00edtico"},"previousItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/#listItem","position":3,"name":"La \u201cconsulta\u201d del PLD otra vez en el centro del debate pol\u00edtico","previousItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/politica\/#listItem","name":"Pol\u00edtica"}}]},{"@type":"Organization","@id":"https:\/\/azuaalinstante.com\/#organization","name":"AZUA AL INSTANTE","description":"SIEMPRE DETR\u00c1S DE LA NOTICIA!","url":"https:\/\/azuaalinstante.com\/"},{"@type":"Person","@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author","url":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/","name":"Redacci\u00f3n","image":{"@type":"ImageObject","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/d68b136e956cb2c839632b9025c3df5f0812f547e1ff3ca13ce11a5b13bf209c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Redacci\u00f3n"}},{"@type":"WebPage","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/#webpage","url":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/","name":"La \u201cconsulta\u201d del PLD otra vez en el centro del debate pol\u00edtico - AZUA AL INSTANTE","description":"La respuesta de la JCE al requerimiento de Dom\u00ednguez Brito, ha reavivado el debate sobre si el proceso se adec\u00faa a las leyes electorales o no. La noche del pasado jueves, la Junta Central Electoral (JCE) se\u00f1al\u00f3 que el proceso de \"consulta interna\" que pretende realizar el Partido de la Liberaci\u00f3n Dominicana (PLD), para escoger","inLanguage":"es-DO","isPartOf":{"@id":"https:\/\/azuaalinstante.com\/#website"},"breadcrumb":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/#breadcrumblist"},"author":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"creator":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/azuaalinstante.com\/wp-content\/uploads\/2026\/06\/675ef43680637.jpeg","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/#mainImage"},"datePublished":"2026-06-30T11:25:25+00:00","dateModified":"2026-06-30T11:25:26+00:00"},{"@type":"WebSite","@id":"https:\/\/azuaalinstante.com\/#website","url":"https:\/\/azuaalinstante.com\/","name":"AZUA AL INSTANTE","description":"SIEMPRE DETR\u00c1S DE LA NOTICIA!","inLanguage":"es-DO","publisher":{"@id":"https:\/\/azuaalinstante.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"AZUA AL INSTANTE - SIEMPRE DETR\u00c1S DE LA NOTICIA!","og:type":"article","og:title":"La \u201cconsulta\u201d del PLD otra vez en el centro del debate pol\u00edtico - AZUA AL INSTANTE","og:description":"La respuesta de la JCE al requerimiento de Dom\u00ednguez Brito, ha reavivado el debate sobre si el proceso se adec\u00faa a las leyes electorales o no. La noche del pasado jueves, la Junta Central Electoral (JCE) se\u00f1al\u00f3 que el proceso de &quot;consulta interna&quot; que pretende realizar el Partido de la Liberaci\u00f3n Dominicana (PLD), para escoger","og:url":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/","article:published_time":"2026-06-30T11:25:25+00:00","article:modified_time":"2026-06-30T11:25:26+00:00","twitter:card":"summary_large_image","twitter:title":"La \u201cconsulta\u201d del PLD otra vez en el centro del debate pol\u00edtico - AZUA AL INSTANTE","twitter:description":"La respuesta de la JCE al requerimiento de Dom\u00ednguez Brito, ha reavivado el debate sobre si el proceso se adec\u00faa a las leyes electorales o no. La noche del pasado jueves, la Junta Central Electoral (JCE) se\u00f1al\u00f3 que el proceso de &quot;consulta interna&quot; que pretende realizar el Partido de la Liberaci\u00f3n Dominicana (PLD), para escoger"},"aioseo_meta_data":{"post_id":"11041","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-06-30 11:25:26","updated":"2026-06-30 12:15:20","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/azuaalinstante.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/azuaalinstante.com\/index.php\/category\/politica\/\" title=\"Pol\u00edtica\">Pol\u00edtica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa \u201cconsulta\u201d del PLD otra vez en el centro del debate pol\u00edtico\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/azuaalinstante.com"},{"label":"Pol\u00edtica","link":"https:\/\/azuaalinstante.com\/index.php\/category\/politica\/"},{"label":"La \u201cconsulta\u201d del PLD otra vez en el centro del debate pol\u00edtico","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/la-consulta-del-pld-otra-vez-en-el-centro-del-debate-politico\/"}],"_links":{"self":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/11041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/comments?post=11041"}],"version-history":[{"count":1,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/11041\/revisions"}],"predecessor-version":[{"id":11043,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/11041\/revisions\/11043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media\/11042"}],"wp:attachment":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media?parent=11041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/categories?post=11041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/tags?post=11041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}