{"id":11075,"date":"2026-06-30T11:48:28","date_gmt":"2026-06-30T11:48:28","guid":{"rendered":"https:\/\/azuaalinstante.com\/?p=11075"},"modified":"2026-06-30T11:48:29","modified_gmt":"2026-06-30T11:48:29","slug":"dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa","status":"publish","type":"post","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/","title":{"rendered":"Dictan 18 meses de prisi\u00f3n preventiva a expresidente del Patronato del Oncol\u00f3gico del Cibao y su esposa"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Tribunal declara complejo el caso Onco 14; excontable obtiene prisi\u00f3n domiciliaria tras admitir hechos y colaborar con la investigaci\u00f3n del Ministerio P\u00fablico.<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/vertical_main_image\/uploads\/2026\/06\/29\/6a432bf5b7404.jpeg\" alt=\"Imputados en el Caso Onco 14\"\/><figcaption class=\"wp-element-caption\">Imputados en el Caso Onco 14Onelio Dom\u00ednguez<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La jueza Stephanie Santiago Reyes, de la Oficina Judicial de Servicios de Atenci\u00f3n Permanente de Santiago, impuso 18 meses de prisi\u00f3n preventiva al expresidente de la Junta Directiva y del Patronato que administra el Instituto Oncol\u00f3gico Regional del Cibao (IORC), H\u00e9ctor Antonio Lora Cruceta, y a su esposa, Luisa Guzm\u00e1n, al considerar que existen elementos probatorios suficientes que los vinculan con la presunta estructura de corrupci\u00f3n desmantelada mediante la Operaci\u00f3n Onco 14.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tribunal declara complejo el caso Onco 14; excontable obtiene prisi\u00f3n domiciliaria tras admitir hechos y colaborar con la investigaci\u00f3n del Ministerio P\u00fablico. La jueza Stephanie Santiago Reyes, de la Oficina Judicial de Servicios de Atenci\u00f3n Permanente de Santiago, impuso 18 meses de prisi\u00f3n preventiva al expresidente de la Junta Directiva y del Patronato que administra [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11076,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Tribunal declara complejo el caso Onco 14; excontable obtiene prisi\u00f3n domiciliaria tras admitir hechos y colaborar con la investigaci\u00f3n del Ministerio P\u00fablico. La jueza Stephanie Santiago Reyes, de la Oficina Judicial de Servicios de Atenci\u00f3n Permanente de Santiago, impuso 18 meses de prisi\u00f3n preventiva al expresidente de la Junta Directiva y del Patronato que administra\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Redacci\u00f3n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"AZUA AL INSTANTE - SIEMPRE DETR\u00c1S DE LA NOTICIA!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Dictan 18 meses de prisi\u00f3n preventiva a expresidente del Patronato del Oncol\u00f3gico del Cibao y su esposa - AZUA AL INSTANTE\" \/>\n\t\t<meta property=\"og:description\" content=\"Tribunal declara complejo el caso Onco 14; excontable obtiene prisi\u00f3n domiciliaria tras admitir hechos y colaborar con la investigaci\u00f3n del Ministerio P\u00fablico. La jueza Stephanie Santiago Reyes, de la Oficina Judicial de Servicios de Atenci\u00f3n Permanente de Santiago, impuso 18 meses de prisi\u00f3n preventiva al expresidente de la Junta Directiva y del Patronato que administra\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-06-30T11:48:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-30T11:48:29+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Dictan 18 meses de prisi\u00f3n preventiva a expresidente del Patronato del Oncol\u00f3gico del Cibao y su esposa - AZUA AL INSTANTE\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Tribunal declara complejo el caso Onco 14; excontable obtiene prisi\u00f3n domiciliaria tras admitir hechos y colaborar con la investigaci\u00f3n del Ministerio P\u00fablico. La jueza Stephanie Santiago Reyes, de la Oficina Judicial de Servicios de Atenci\u00f3n Permanente de Santiago, impuso 18 meses de prisi\u00f3n preventiva al expresidente de la Junta Directiva y del Patronato que administra\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\\\/#blogposting\",\"name\":\"Dictan 18 meses de prisi\\u00f3n preventiva a expresidente del Patronato del Oncol\\u00f3gico del Cibao y su esposa - AZUA AL INSTANTE\",\"headline\":\"Dictan 18 meses de prisi\\u00f3n preventiva a expresidente del Patronato del Oncol\\u00f3gico del Cibao y su esposa\",\"author\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/6a432bf5b7404.jpeg\",\"width\":800,\"height\":450},\"datePublished\":\"2026-06-30T11:48:28+00:00\",\"dateModified\":\"2026-06-30T11:48:29+00:00\",\"inLanguage\":\"es-DO\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\\\/#webpage\"},\"articleSection\":\"Deporte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/azuaalinstante.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/uncategorized\\\/#listItem\",\"name\":\"Deporte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/uncategorized\\\/#listItem\",\"position\":3,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\\\/#listItem\",\"name\":\"Dictan 18 meses de prisi\\u00f3n preventiva a expresidente del Patronato del Oncol\\u00f3gico del Cibao y su esposa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\\\/#listItem\",\"position\":4,\"name\":\"Dictan 18 meses de prisi\\u00f3n preventiva a expresidente del Patronato del Oncol\\u00f3gico del Cibao y su esposa\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/uncategorized\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\",\"name\":\"AZUA AL INSTANTE\",\"description\":\"SIEMPRE DETR\\u00c1S DE LA NOTICIA!\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/\",\"name\":\"Redacci\\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d68b136e956cb2c839632b9025c3df5f0812f547e1ff3ca13ce11a5b13bf209c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Redacci\\u00f3n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\\\/#webpage\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\\\/\",\"name\":\"Dictan 18 meses de prisi\\u00f3n preventiva a expresidente del Patronato del Oncol\\u00f3gico del Cibao y su esposa - AZUA AL INSTANTE\",\"description\":\"Tribunal declara complejo el caso Onco 14; excontable obtiene prisi\\u00f3n domiciliaria tras admitir hechos y colaborar con la investigaci\\u00f3n del Ministerio P\\u00fablico. La jueza Stephanie Santiago Reyes, de la Oficina Judicial de Servicios de Atenci\\u00f3n Permanente de Santiago, impuso 18 meses de prisi\\u00f3n preventiva al expresidente de la Junta Directiva y del Patronato que administra\",\"inLanguage\":\"es-DO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/6a432bf5b7404.jpeg\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\\\/#mainImage\",\"width\":800,\"height\":450},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/06\\\/30\\\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\\\/#mainImage\"},\"datePublished\":\"2026-06-30T11:48:28+00:00\",\"dateModified\":\"2026-06-30T11:48:29+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#website\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/\",\"name\":\"AZUA AL INSTANTE\",\"description\":\"SIEMPRE DETR\\u00c1S DE LA NOTICIA!\",\"inLanguage\":\"es-DO\",\"publisher\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Dictan 18 meses de prisi\u00f3n preventiva a expresidente del Patronato del Oncol\u00f3gico del Cibao y su esposa - AZUA AL INSTANTE","description":"Tribunal declara complejo el caso Onco 14; excontable obtiene prisi\u00f3n domiciliaria tras admitir hechos y colaborar con la investigaci\u00f3n del Ministerio P\u00fablico. La jueza Stephanie Santiago Reyes, de la Oficina Judicial de Servicios de Atenci\u00f3n Permanente de Santiago, impuso 18 meses de prisi\u00f3n preventiva al expresidente de la Junta Directiva y del Patronato que administra","canonical_url":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/#blogposting","name":"Dictan 18 meses de prisi\u00f3n preventiva a expresidente del Patronato del Oncol\u00f3gico del Cibao y su esposa - AZUA AL INSTANTE","headline":"Dictan 18 meses de prisi\u00f3n preventiva a expresidente del Patronato del Oncol\u00f3gico del Cibao y su esposa","author":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"publisher":{"@id":"https:\/\/azuaalinstante.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/azuaalinstante.com\/wp-content\/uploads\/2026\/06\/6a432bf5b7404.jpeg","width":800,"height":450},"datePublished":"2026-06-30T11:48:28+00:00","dateModified":"2026-06-30T11:48:29+00:00","inLanguage":"es-DO","mainEntityOfPage":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/#webpage"},"isPartOf":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/#webpage"},"articleSection":"Deporte"},{"@type":"BreadcrumbList","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com#listItem","position":1,"name":"Home","item":"https:\/\/azuaalinstante.com","nextItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/#listItem","position":2,"name":"Deportes","item":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/uncategorized\/#listItem","name":"Deporte"},"previousItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/uncategorized\/#listItem","position":3,"name":"Deporte","item":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/#listItem","name":"Dictan 18 meses de prisi\u00f3n preventiva a expresidente del Patronato del Oncol\u00f3gico del Cibao y su esposa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/#listItem","position":4,"name":"Dictan 18 meses de prisi\u00f3n preventiva a expresidente del Patronato del Oncol\u00f3gico del Cibao y su esposa","previousItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/uncategorized\/#listItem","name":"Deporte"}}]},{"@type":"Organization","@id":"https:\/\/azuaalinstante.com\/#organization","name":"AZUA AL INSTANTE","description":"SIEMPRE DETR\u00c1S DE LA NOTICIA!","url":"https:\/\/azuaalinstante.com\/"},{"@type":"Person","@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author","url":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/","name":"Redacci\u00f3n","image":{"@type":"ImageObject","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/d68b136e956cb2c839632b9025c3df5f0812f547e1ff3ca13ce11a5b13bf209c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Redacci\u00f3n"}},{"@type":"WebPage","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/#webpage","url":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/","name":"Dictan 18 meses de prisi\u00f3n preventiva a expresidente del Patronato del Oncol\u00f3gico del Cibao y su esposa - AZUA AL INSTANTE","description":"Tribunal declara complejo el caso Onco 14; excontable obtiene prisi\u00f3n domiciliaria tras admitir hechos y colaborar con la investigaci\u00f3n del Ministerio P\u00fablico. La jueza Stephanie Santiago Reyes, de la Oficina Judicial de Servicios de Atenci\u00f3n Permanente de Santiago, impuso 18 meses de prisi\u00f3n preventiva al expresidente de la Junta Directiva y del Patronato que administra","inLanguage":"es-DO","isPartOf":{"@id":"https:\/\/azuaalinstante.com\/#website"},"breadcrumb":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/#breadcrumblist"},"author":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"creator":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/azuaalinstante.com\/wp-content\/uploads\/2026\/06\/6a432bf5b7404.jpeg","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/#mainImage","width":800,"height":450},"primaryImageOfPage":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/#mainImage"},"datePublished":"2026-06-30T11:48:28+00:00","dateModified":"2026-06-30T11:48:29+00:00"},{"@type":"WebSite","@id":"https:\/\/azuaalinstante.com\/#website","url":"https:\/\/azuaalinstante.com\/","name":"AZUA AL INSTANTE","description":"SIEMPRE DETR\u00c1S DE LA NOTICIA!","inLanguage":"es-DO","publisher":{"@id":"https:\/\/azuaalinstante.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"AZUA AL INSTANTE - SIEMPRE DETR\u00c1S DE LA NOTICIA!","og:type":"article","og:title":"Dictan 18 meses de prisi\u00f3n preventiva a expresidente del Patronato del Oncol\u00f3gico del Cibao y su esposa - AZUA AL INSTANTE","og:description":"Tribunal declara complejo el caso Onco 14; excontable obtiene prisi\u00f3n domiciliaria tras admitir hechos y colaborar con la investigaci\u00f3n del Ministerio P\u00fablico. La jueza Stephanie Santiago Reyes, de la Oficina Judicial de Servicios de Atenci\u00f3n Permanente de Santiago, impuso 18 meses de prisi\u00f3n preventiva al expresidente de la Junta Directiva y del Patronato que administra","og:url":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/","article:published_time":"2026-06-30T11:48:28+00:00","article:modified_time":"2026-06-30T11:48:29+00:00","twitter:card":"summary_large_image","twitter:title":"Dictan 18 meses de prisi\u00f3n preventiva a expresidente del Patronato del Oncol\u00f3gico del Cibao y su esposa - AZUA AL INSTANTE","twitter:description":"Tribunal declara complejo el caso Onco 14; excontable obtiene prisi\u00f3n domiciliaria tras admitir hechos y colaborar con la investigaci\u00f3n del Ministerio P\u00fablico. La jueza Stephanie Santiago Reyes, de la Oficina Judicial de Servicios de Atenci\u00f3n Permanente de Santiago, impuso 18 meses de prisi\u00f3n preventiva al expresidente de la Junta Directiva y del Patronato que administra"},"aioseo_meta_data":{"post_id":"11075","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-06-30 11:48:29","updated":"2026-06-30 12:16:23","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/azuaalinstante.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/\" title=\"Deportes\">Deportes<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/uncategorized\/\" title=\"Deporte\">Deporte<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDictan 18 meses de prisi\u00f3n preventiva a expresidente del Patronato del Oncol\u00f3gico del Cibao y su esposa\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/azuaalinstante.com"},{"label":"Deportes","link":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/"},{"label":"Deporte","link":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/uncategorized\/"},{"label":"Dictan 18 meses de prisi\u00f3n preventiva a expresidente del Patronato del Oncol\u00f3gico del Cibao y su esposa","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/06\/30\/dictan-18-meses-de-prision-preventiva-a-expresidente-del-patronato-del-oncologico-del-cibao-y-su-esposa\/"}],"_links":{"self":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/11075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/comments?post=11075"}],"version-history":[{"count":1,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/11075\/revisions"}],"predecessor-version":[{"id":11077,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/11075\/revisions\/11077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media\/11076"}],"wp:attachment":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media?parent=11075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/categories?post=11075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/tags?post=11075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}