{"id":11927,"date":"2026-07-13T10:45:47","date_gmt":"2026-07-13T10:45:47","guid":{"rendered":"https:\/\/azuaalinstante.com\/?p=11927"},"modified":"2026-07-13T10:45:48","modified_gmt":"2026-07-13T10:45:48","slug":"hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras","status":"publish","type":"post","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/","title":{"rendered":"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La licitaci\u00f3n para transformar el principal mercado de Santiago fue adjudicada hace meses, pero comerciantes y residentes aseguran que las condiciones que dieron origen al proyecto permanecen sin cambios.<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/square_main_image\/uploads\/2026\/07\/12\/6a54239971e0c.jpeg\" alt=\"La acumulaci\u00f3n de basura y malos olores en el  mercado dificulta la movilidad de vendedores y compradores.\"\/><figcaption class=\"wp-element-caption\">La acumulaci\u00f3n de basura y malos olores en el mercado dificulta la movilidad de vendedores y compradores.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">pujols Santiago, RD<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Han transcurrido cerca de diez meses desde que el presidente Luis Abinader anunci\u00f3 una inversi\u00f3n de RD$658 millones para transformar el Hospedaje Yaque y el sector Nueva York Chiquito, en Santiago.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La licitaci\u00f3n para transformar el principal mercado de Santiago fue adjudicada hace meses, pero comerciantes y residentes aseguran que las condiciones que dieron origen al proyecto permanecen sin cambios. pujols Santiago, RD Han transcurrido cerca de diez meses desde que el presidente Luis Abinader anunci\u00f3 una inversi\u00f3n de RD$658 millones para transformar el Hospedaje Yaque [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11928,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-11927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-republica"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"La licitaci\u00f3n para transformar el principal mercado de Santiago fue adjudicada hace meses, pero comerciantes y residentes aseguran que las condiciones que dieron origen al proyecto permanecen sin cambios. pujols Santiago, RD Han transcurrido cerca de diez meses desde que el presidente Luis Abinader anunci\u00f3 una inversi\u00f3n de RD$658 millones para transformar el Hospedaje Yaque\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Redacci\u00f3n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"AZUA AL INSTANTE - SIEMPRE DETR\u00c1S DE LA NOTICIA!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras - AZUA AL INSTANTE\" \/>\n\t\t<meta property=\"og:description\" content=\"La licitaci\u00f3n para transformar el principal mercado de Santiago fue adjudicada hace meses, pero comerciantes y residentes aseguran que las condiciones que dieron origen al proyecto permanecen sin cambios. pujols Santiago, RD Han transcurrido cerca de diez meses desde que el presidente Luis Abinader anunci\u00f3 una inversi\u00f3n de RD$658 millones para transformar el Hospedaje Yaque\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-13T10:45:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-13T10:45:48+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras - AZUA AL INSTANTE\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La licitaci\u00f3n para transformar el principal mercado de Santiago fue adjudicada hace meses, pero comerciantes y residentes aseguran que las condiciones que dieron origen al proyecto permanecen sin cambios. pujols Santiago, RD Han transcurrido cerca de diez meses desde que el presidente Luis Abinader anunci\u00f3 una inversi\u00f3n de RD$658 millones para transformar el Hospedaje Yaque\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\\\/#blogposting\",\"name\":\"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras - AZUA AL INSTANTE\",\"headline\":\"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras\",\"author\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/6a54239971e0c.jpeg\",\"width\":628,\"height\":537},\"datePublished\":\"2026-07-13T10:45:47+00:00\",\"dateModified\":\"2026-07-13T10:45:48+00:00\",\"inLanguage\":\"es-DO\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\\\/#webpage\"},\"articleSection\":\"Rep\\u00fablica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/azuaalinstante.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/republica\\\/#listItem\",\"name\":\"Rep\\u00fablica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/republica\\\/#listItem\",\"position\":2,\"name\":\"Rep\\u00fablica\",\"item\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/republica\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\\\/#listItem\",\"name\":\"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\\\/#listItem\",\"position\":3,\"name\":\"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/republica\\\/#listItem\",\"name\":\"Rep\\u00fablica\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\",\"name\":\"AZUA AL INSTANTE\",\"description\":\"SIEMPRE DETR\\u00c1S DE LA NOTICIA!\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/\",\"name\":\"Redacci\\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d68b136e956cb2c839632b9025c3df5f0812f547e1ff3ca13ce11a5b13bf209c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Redacci\\u00f3n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\\\/#webpage\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\\\/\",\"name\":\"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras - AZUA AL INSTANTE\",\"description\":\"La licitaci\\u00f3n para transformar el principal mercado de Santiago fue adjudicada hace meses, pero comerciantes y residentes aseguran que las condiciones que dieron origen al proyecto permanecen sin cambios. pujols Santiago, RD Han transcurrido cerca de diez meses desde que el presidente Luis Abinader anunci\\u00f3 una inversi\\u00f3n de RD$658 millones para transformar el Hospedaje Yaque\",\"inLanguage\":\"es-DO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/6a54239971e0c.jpeg\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\\\/#mainImage\",\"width\":628,\"height\":537},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\\\/#mainImage\"},\"datePublished\":\"2026-07-13T10:45:47+00:00\",\"dateModified\":\"2026-07-13T10:45:48+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#website\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/\",\"name\":\"AZUA AL INSTANTE\",\"description\":\"SIEMPRE DETR\\u00c1S DE LA NOTICIA!\",\"inLanguage\":\"es-DO\",\"publisher\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras - AZUA AL INSTANTE","description":"La licitaci\u00f3n para transformar el principal mercado de Santiago fue adjudicada hace meses, pero comerciantes y residentes aseguran que las condiciones que dieron origen al proyecto permanecen sin cambios. pujols Santiago, RD Han transcurrido cerca de diez meses desde que el presidente Luis Abinader anunci\u00f3 una inversi\u00f3n de RD$658 millones para transformar el Hospedaje Yaque","canonical_url":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/#blogposting","name":"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras - AZUA AL INSTANTE","headline":"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras","author":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"publisher":{"@id":"https:\/\/azuaalinstante.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/azuaalinstante.com\/wp-content\/uploads\/2026\/07\/6a54239971e0c.jpeg","width":628,"height":537},"datePublished":"2026-07-13T10:45:47+00:00","dateModified":"2026-07-13T10:45:48+00:00","inLanguage":"es-DO","mainEntityOfPage":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/#webpage"},"isPartOf":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/#webpage"},"articleSection":"Rep\u00fablica"},{"@type":"BreadcrumbList","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com#listItem","position":1,"name":"Home","item":"https:\/\/azuaalinstante.com","nextItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/republica\/#listItem","name":"Rep\u00fablica"}},{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/republica\/#listItem","position":2,"name":"Rep\u00fablica","item":"https:\/\/azuaalinstante.com\/index.php\/category\/republica\/","nextItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/#listItem","name":"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras"},"previousItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/#listItem","position":3,"name":"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras","previousItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/republica\/#listItem","name":"Rep\u00fablica"}}]},{"@type":"Organization","@id":"https:\/\/azuaalinstante.com\/#organization","name":"AZUA AL INSTANTE","description":"SIEMPRE DETR\u00c1S DE LA NOTICIA!","url":"https:\/\/azuaalinstante.com\/"},{"@type":"Person","@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author","url":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/","name":"Redacci\u00f3n","image":{"@type":"ImageObject","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/d68b136e956cb2c839632b9025c3df5f0812f547e1ff3ca13ce11a5b13bf209c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Redacci\u00f3n"}},{"@type":"WebPage","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/#webpage","url":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/","name":"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras - AZUA AL INSTANTE","description":"La licitaci\u00f3n para transformar el principal mercado de Santiago fue adjudicada hace meses, pero comerciantes y residentes aseguran que las condiciones que dieron origen al proyecto permanecen sin cambios. pujols Santiago, RD Han transcurrido cerca de diez meses desde que el presidente Luis Abinader anunci\u00f3 una inversi\u00f3n de RD$658 millones para transformar el Hospedaje Yaque","inLanguage":"es-DO","isPartOf":{"@id":"https:\/\/azuaalinstante.com\/#website"},"breadcrumb":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/#breadcrumblist"},"author":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"creator":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/azuaalinstante.com\/wp-content\/uploads\/2026\/07\/6a54239971e0c.jpeg","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/#mainImage","width":628,"height":537},"primaryImageOfPage":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/#mainImage"},"datePublished":"2026-07-13T10:45:47+00:00","dateModified":"2026-07-13T10:45:48+00:00"},{"@type":"WebSite","@id":"https:\/\/azuaalinstante.com\/#website","url":"https:\/\/azuaalinstante.com\/","name":"AZUA AL INSTANTE","description":"SIEMPRE DETR\u00c1S DE LA NOTICIA!","inLanguage":"es-DO","publisher":{"@id":"https:\/\/azuaalinstante.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"AZUA AL INSTANTE - SIEMPRE DETR\u00c1S DE LA NOTICIA!","og:type":"article","og:title":"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras - AZUA AL INSTANTE","og:description":"La licitaci\u00f3n para transformar el principal mercado de Santiago fue adjudicada hace meses, pero comerciantes y residentes aseguran que las condiciones que dieron origen al proyecto permanecen sin cambios. pujols Santiago, RD Han transcurrido cerca de diez meses desde que el presidente Luis Abinader anunci\u00f3 una inversi\u00f3n de RD$658 millones para transformar el Hospedaje Yaque","og:url":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/","article:published_time":"2026-07-13T10:45:47+00:00","article:modified_time":"2026-07-13T10:45:48+00:00","twitter:card":"summary_large_image","twitter:title":"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras - AZUA AL INSTANTE","twitter:description":"La licitaci\u00f3n para transformar el principal mercado de Santiago fue adjudicada hace meses, pero comerciantes y residentes aseguran que las condiciones que dieron origen al proyecto permanecen sin cambios. pujols Santiago, RD Han transcurrido cerca de diez meses desde que el presidente Luis Abinader anunci\u00f3 una inversi\u00f3n de RD$658 millones para transformar el Hospedaje Yaque"},"aioseo_meta_data":{"post_id":"11927","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-13 10:45:48","updated":"2026-07-13 16:04:44","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/azuaalinstante.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/azuaalinstante.com\/index.php\/category\/republica\/\" title=\"Rep\u00fablica\">Rep\u00fablica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/azuaalinstante.com"},{"label":"Rep\u00fablica","link":"https:\/\/azuaalinstante.com\/index.php\/category\/republica\/"},{"label":"Hospedaje Yaque: Diez meses de promesas y desorden sin que inicien las obras","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/hospedaje-yaque-diez-meses-de-promesas-y-desorden-sin-que-inicien-las-obras\/"}],"_links":{"self":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/11927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/comments?post=11927"}],"version-history":[{"count":1,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/11927\/revisions"}],"predecessor-version":[{"id":11929,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/11927\/revisions\/11929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media\/11928"}],"wp:attachment":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media?parent=11927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/categories?post=11927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/tags?post=11927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}