{"id":11950,"date":"2026-07-13T11:15:27","date_gmt":"2026-07-13T11:15:27","guid":{"rendered":"https:\/\/azuaalinstante.com\/?p=11950"},"modified":"2026-07-13T11:15:28","modified_gmt":"2026-07-13T11:15:28","slug":"juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets","status":"publish","type":"post","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/","title":{"rendered":"Juan Soto agradece el respaldo de fan\u00e1ticos y mantiene fe en Mets"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El jardinero dominicano afirma que su prioridad es ayudar al equipo a ganar.&nbsp;<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Admite que la salida de Carlos Mendoza fue \"bastante fuerte\".<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/vertical_main_image\/uploads\/2026\/07\/12\/6a540d3941fea.jpeg\" alt=\"Juan Soto responde una de las cuestionantes durante una rueda de prensa.\"\/><figcaption class=\"wp-element-caption\">Juan Soto responde una de las cuestionantes durante una rueda de prensa.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Juan Soto agradeci\u00f3 el respaldo recibido por los fan\u00e1ticos tras ser elegido como jardinero titular para el Juego de las Estrellas y asegur\u00f3 que ese reconocimiento representa un orgullo tanto para \u00e9l como para la Rep\u00fablica Dominicana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jardinero dominicano afirma que su prioridad es ayudar al equipo a ganar.&nbsp; Juan Soto agradeci\u00f3 el respaldo recibido por los fan\u00e1ticos tras ser elegido como jardinero titular para el Juego de las Estrellas y asegur\u00f3 que ese reconocimiento representa un orgullo tanto para \u00e9l como para la Rep\u00fablica Dominicana.<\/p>\n","protected":false},"author":2,"featured_media":11951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"El jardinero dominicano afirma que su prioridad es ayudar al equipo a ganar. Admite que la salida de Carlos Mendoza fue &quot;bastante fuerte&quot;. Juan Soto agradeci\u00f3 el respaldo recibido por los fan\u00e1ticos tras ser elegido como jardinero titular para el Juego de las Estrellas y asegur\u00f3 que ese reconocimiento representa un orgullo tanto para \u00e9l\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Redacci\u00f3n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"AZUA AL INSTANTE - SIEMPRE DETR\u00c1S DE LA NOTICIA!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Juan Soto agradece el respaldo de fan\u00e1ticos y mantiene fe en Mets - AZUA AL INSTANTE\" \/>\n\t\t<meta property=\"og:description\" content=\"El jardinero dominicano afirma que su prioridad es ayudar al equipo a ganar. Admite que la salida de Carlos Mendoza fue &quot;bastante fuerte&quot;. Juan Soto agradeci\u00f3 el respaldo recibido por los fan\u00e1ticos tras ser elegido como jardinero titular para el Juego de las Estrellas y asegur\u00f3 que ese reconocimiento representa un orgullo tanto para \u00e9l\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-13T11:15:27+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-13T11:15:28+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Juan Soto agradece el respaldo de fan\u00e1ticos y mantiene fe en Mets - AZUA AL INSTANTE\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El jardinero dominicano afirma que su prioridad es ayudar al equipo a ganar. Admite que la salida de Carlos Mendoza fue &quot;bastante fuerte&quot;. Juan Soto agradeci\u00f3 el respaldo recibido por los fan\u00e1ticos tras ser elegido como jardinero titular para el Juego de las Estrellas y asegur\u00f3 que ese reconocimiento representa un orgullo tanto para \u00e9l\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\\\/#blogposting\",\"name\":\"Juan Soto agradece el respaldo de fan\\u00e1ticos y mantiene fe en Mets - AZUA AL INSTANTE\",\"headline\":\"Juan Soto agradece el respaldo de fan\\u00e1ticos y mantiene fe en Mets\",\"author\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/6a540d3941fea.jpeg\",\"width\":800,\"height\":498},\"datePublished\":\"2026-07-13T11:15:27+00:00\",\"dateModified\":\"2026-07-13T11:15:28+00:00\",\"inLanguage\":\"es-DO\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\\\/#webpage\"},\"articleSection\":\"Deporte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/azuaalinstante.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/uncategorized\\\/#listItem\",\"name\":\"Deporte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/uncategorized\\\/#listItem\",\"position\":3,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\\\/#listItem\",\"name\":\"Juan Soto agradece el respaldo de fan\\u00e1ticos y mantiene fe en Mets\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\\\/#listItem\",\"position\":4,\"name\":\"Juan Soto agradece el respaldo de fan\\u00e1ticos y mantiene fe en Mets\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/deportes\\\/uncategorized\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\",\"name\":\"AZUA AL INSTANTE\",\"description\":\"SIEMPRE DETR\\u00c1S DE LA NOTICIA!\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/\",\"name\":\"Redacci\\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d68b136e956cb2c839632b9025c3df5f0812f547e1ff3ca13ce11a5b13bf209c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Redacci\\u00f3n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\\\/#webpage\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\\\/\",\"name\":\"Juan Soto agradece el respaldo de fan\\u00e1ticos y mantiene fe en Mets - AZUA AL INSTANTE\",\"description\":\"El jardinero dominicano afirma que su prioridad es ayudar al equipo a ganar. Admite que la salida de Carlos Mendoza fue \\\"bastante fuerte\\\". Juan Soto agradeci\\u00f3 el respaldo recibido por los fan\\u00e1ticos tras ser elegido como jardinero titular para el Juego de las Estrellas y asegur\\u00f3 que ese reconocimiento representa un orgullo tanto para \\u00e9l\",\"inLanguage\":\"es-DO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/6a540d3941fea.jpeg\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\\\/#mainImage\",\"width\":800,\"height\":498},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/13\\\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\\\/#mainImage\"},\"datePublished\":\"2026-07-13T11:15:27+00:00\",\"dateModified\":\"2026-07-13T11:15:28+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#website\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/\",\"name\":\"AZUA AL INSTANTE\",\"description\":\"SIEMPRE DETR\\u00c1S DE LA NOTICIA!\",\"inLanguage\":\"es-DO\",\"publisher\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Juan Soto agradece el respaldo de fan\u00e1ticos y mantiene fe en Mets - AZUA AL INSTANTE","description":"El jardinero dominicano afirma que su prioridad es ayudar al equipo a ganar. Admite que la salida de Carlos Mendoza fue \"bastante fuerte\". Juan Soto agradeci\u00f3 el respaldo recibido por los fan\u00e1ticos tras ser elegido como jardinero titular para el Juego de las Estrellas y asegur\u00f3 que ese reconocimiento representa un orgullo tanto para \u00e9l","canonical_url":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/#blogposting","name":"Juan Soto agradece el respaldo de fan\u00e1ticos y mantiene fe en Mets - AZUA AL INSTANTE","headline":"Juan Soto agradece el respaldo de fan\u00e1ticos y mantiene fe en Mets","author":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"publisher":{"@id":"https:\/\/azuaalinstante.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/azuaalinstante.com\/wp-content\/uploads\/2026\/07\/6a540d3941fea.jpeg","width":800,"height":498},"datePublished":"2026-07-13T11:15:27+00:00","dateModified":"2026-07-13T11:15:28+00:00","inLanguage":"es-DO","mainEntityOfPage":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/#webpage"},"isPartOf":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/#webpage"},"articleSection":"Deporte"},{"@type":"BreadcrumbList","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com#listItem","position":1,"name":"Home","item":"https:\/\/azuaalinstante.com","nextItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/#listItem","position":2,"name":"Deportes","item":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/uncategorized\/#listItem","name":"Deporte"},"previousItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/uncategorized\/#listItem","position":3,"name":"Deporte","item":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/#listItem","name":"Juan Soto agradece el respaldo de fan\u00e1ticos y mantiene fe en Mets"},"previousItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/#listItem","position":4,"name":"Juan Soto agradece el respaldo de fan\u00e1ticos y mantiene fe en Mets","previousItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/uncategorized\/#listItem","name":"Deporte"}}]},{"@type":"Organization","@id":"https:\/\/azuaalinstante.com\/#organization","name":"AZUA AL INSTANTE","description":"SIEMPRE DETR\u00c1S DE LA NOTICIA!","url":"https:\/\/azuaalinstante.com\/"},{"@type":"Person","@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author","url":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/","name":"Redacci\u00f3n","image":{"@type":"ImageObject","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/d68b136e956cb2c839632b9025c3df5f0812f547e1ff3ca13ce11a5b13bf209c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Redacci\u00f3n"}},{"@type":"WebPage","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/#webpage","url":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/","name":"Juan Soto agradece el respaldo de fan\u00e1ticos y mantiene fe en Mets - AZUA AL INSTANTE","description":"El jardinero dominicano afirma que su prioridad es ayudar al equipo a ganar. Admite que la salida de Carlos Mendoza fue \"bastante fuerte\". Juan Soto agradeci\u00f3 el respaldo recibido por los fan\u00e1ticos tras ser elegido como jardinero titular para el Juego de las Estrellas y asegur\u00f3 que ese reconocimiento representa un orgullo tanto para \u00e9l","inLanguage":"es-DO","isPartOf":{"@id":"https:\/\/azuaalinstante.com\/#website"},"breadcrumb":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/#breadcrumblist"},"author":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"creator":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/azuaalinstante.com\/wp-content\/uploads\/2026\/07\/6a540d3941fea.jpeg","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/#mainImage","width":800,"height":498},"primaryImageOfPage":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/#mainImage"},"datePublished":"2026-07-13T11:15:27+00:00","dateModified":"2026-07-13T11:15:28+00:00"},{"@type":"WebSite","@id":"https:\/\/azuaalinstante.com\/#website","url":"https:\/\/azuaalinstante.com\/","name":"AZUA AL INSTANTE","description":"SIEMPRE DETR\u00c1S DE LA NOTICIA!","inLanguage":"es-DO","publisher":{"@id":"https:\/\/azuaalinstante.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"AZUA AL INSTANTE - SIEMPRE DETR\u00c1S DE LA NOTICIA!","og:type":"article","og:title":"Juan Soto agradece el respaldo de fan\u00e1ticos y mantiene fe en Mets - AZUA AL INSTANTE","og:description":"El jardinero dominicano afirma que su prioridad es ayudar al equipo a ganar. Admite que la salida de Carlos Mendoza fue &quot;bastante fuerte&quot;. Juan Soto agradeci\u00f3 el respaldo recibido por los fan\u00e1ticos tras ser elegido como jardinero titular para el Juego de las Estrellas y asegur\u00f3 que ese reconocimiento representa un orgullo tanto para \u00e9l","og:url":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/","article:published_time":"2026-07-13T11:15:27+00:00","article:modified_time":"2026-07-13T11:15:28+00:00","twitter:card":"summary_large_image","twitter:title":"Juan Soto agradece el respaldo de fan\u00e1ticos y mantiene fe en Mets - AZUA AL INSTANTE","twitter:description":"El jardinero dominicano afirma que su prioridad es ayudar al equipo a ganar. Admite que la salida de Carlos Mendoza fue &quot;bastante fuerte&quot;. Juan Soto agradeci\u00f3 el respaldo recibido por los fan\u00e1ticos tras ser elegido como jardinero titular para el Juego de las Estrellas y asegur\u00f3 que ese reconocimiento representa un orgullo tanto para \u00e9l"},"aioseo_meta_data":{"post_id":"11950","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-13 11:15:28","updated":"2026-07-13 16:05:51","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/azuaalinstante.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/\" title=\"Deportes\">Deportes<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/uncategorized\/\" title=\"Deporte\">Deporte<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tJuan Soto agradece el respaldo de fan\u00e1ticos y mantiene fe en Mets\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/azuaalinstante.com"},{"label":"Deportes","link":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/"},{"label":"Deporte","link":"https:\/\/azuaalinstante.com\/index.php\/category\/deportes\/uncategorized\/"},{"label":"Juan Soto agradece el respaldo de fan\u00e1ticos y mantiene fe en Mets","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/13\/juan-soto-agradece-el-respaldo-de-fanaticos-y-mantiene-fe-en-mets\/"}],"_links":{"self":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/11950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/comments?post=11950"}],"version-history":[{"count":1,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/11950\/revisions"}],"predecessor-version":[{"id":11952,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/11950\/revisions\/11952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media\/11951"}],"wp:attachment":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media?parent=11950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/categories?post=11950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/tags?post=11950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}