{"id":12040,"date":"2026-07-15T12:50:39","date_gmt":"2026-07-15T12:50:39","guid":{"rendered":"https:\/\/azuaalinstante.com\/?p=12040"},"modified":"2026-07-15T12:51:04","modified_gmt":"2026-07-15T12:51:04","slug":"filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago","status":"publish","type":"post","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/","title":{"rendered":"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El director del Centro Cultural Palacio Consistorial, Rafaelito Mirabal, inform\u00f3 que los da\u00f1os ya fueron comunicados al Ministerio de Cultura, entidad responsable de la conservaci\u00f3n e intervenci\u00f3n de las edificaciones patrimoniales del pa\u00eds.<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/vertical_main_image\/uploads\/2026\/07\/14\/6a56e035319c5.jpeg\" alt=\"El techo del Consistorial revela su estado.\"\/><figcaption class=\"wp-element-caption\">El techo del Consistorial revela su estado.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El Palacio Consistorial de Santiago, uno de los principales centros culturales e hist\u00f3ricos de la Ciudad Coraz\u00f3n, presenta problemas de filtraciones, desprendimiento del techo y un evidente deterioro en distintas \u00e1reas de su estructura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director del Centro Cultural Palacio Consistorial, Rafaelito Mirabal, inform\u00f3 que los da\u00f1os ya fueron comunicados al Ministerio de Cultura, entidad responsable de la conservaci\u00f3n e intervenci\u00f3n de las edificaciones patrimoniales del pa\u00eds. El Palacio Consistorial de Santiago, uno de los principales centros culturales e hist\u00f3ricos de la Ciudad Coraz\u00f3n, presenta problemas de filtraciones, desprendimiento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12041,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-12040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-republica"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"El director del Centro Cultural Palacio Consistorial, Rafaelito Mirabal, inform\u00f3 que los da\u00f1os ya fueron comunicados al Ministerio de Cultura, entidad responsable de la conservaci\u00f3n e intervenci\u00f3n de las edificaciones patrimoniales del pa\u00eds. El Palacio Consistorial de Santiago, uno de los principales centros culturales e hist\u00f3ricos de la Ciudad Coraz\u00f3n, presenta problemas de filtraciones, desprendimiento\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Redacci\u00f3n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"AZUA AL INSTANTE - SIEMPRE DETR\u00c1S DE LA NOTICIA!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago - AZUA AL INSTANTE\" \/>\n\t\t<meta property=\"og:description\" content=\"El director del Centro Cultural Palacio Consistorial, Rafaelito Mirabal, inform\u00f3 que los da\u00f1os ya fueron comunicados al Ministerio de Cultura, entidad responsable de la conservaci\u00f3n e intervenci\u00f3n de las edificaciones patrimoniales del pa\u00eds. El Palacio Consistorial de Santiago, uno de los principales centros culturales e hist\u00f3ricos de la Ciudad Coraz\u00f3n, presenta problemas de filtraciones, desprendimiento\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-15T12:50:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-15T12:51:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago - AZUA AL INSTANTE\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El director del Centro Cultural Palacio Consistorial, Rafaelito Mirabal, inform\u00f3 que los da\u00f1os ya fueron comunicados al Ministerio de Cultura, entidad responsable de la conservaci\u00f3n e intervenci\u00f3n de las edificaciones patrimoniales del pa\u00eds. El Palacio Consistorial de Santiago, uno de los principales centros culturales e hist\u00f3ricos de la Ciudad Coraz\u00f3n, presenta problemas de filtraciones, desprendimiento\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/15\\\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\\\/#blogposting\",\"name\":\"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago - AZUA AL INSTANTE\",\"headline\":\"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago\",\"author\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/6a56e035319c5.jpeg\",\"width\":800,\"height\":600},\"datePublished\":\"2026-07-15T12:50:39+00:00\",\"dateModified\":\"2026-07-15T12:51:04+00:00\",\"inLanguage\":\"es-DO\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/15\\\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/15\\\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\\\/#webpage\"},\"articleSection\":\"Rep\\u00fablica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/15\\\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/azuaalinstante.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/republica\\\/#listItem\",\"name\":\"Rep\\u00fablica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/republica\\\/#listItem\",\"position\":2,\"name\":\"Rep\\u00fablica\",\"item\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/republica\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/15\\\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\\\/#listItem\",\"name\":\"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/15\\\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\\\/#listItem\",\"position\":3,\"name\":\"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/republica\\\/#listItem\",\"name\":\"Rep\\u00fablica\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\",\"name\":\"AZUA AL INSTANTE\",\"description\":\"SIEMPRE DETR\\u00c1S DE LA NOTICIA!\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/\",\"name\":\"Redacci\\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/15\\\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d68b136e956cb2c839632b9025c3df5f0812f547e1ff3ca13ce11a5b13bf209c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Redacci\\u00f3n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/15\\\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\\\/#webpage\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/15\\\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\\\/\",\"name\":\"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago - AZUA AL INSTANTE\",\"description\":\"El director del Centro Cultural Palacio Consistorial, Rafaelito Mirabal, inform\\u00f3 que los da\\u00f1os ya fueron comunicados al Ministerio de Cultura, entidad responsable de la conservaci\\u00f3n e intervenci\\u00f3n de las edificaciones patrimoniales del pa\\u00eds. El Palacio Consistorial de Santiago, uno de los principales centros culturales e hist\\u00f3ricos de la Ciudad Coraz\\u00f3n, presenta problemas de filtraciones, desprendimiento\",\"inLanguage\":\"es-DO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/15\\\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/6a56e035319c5.jpeg\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/15\\\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\\\/#mainImage\",\"width\":800,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/07\\\/15\\\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\\\/#mainImage\"},\"datePublished\":\"2026-07-15T12:50:39+00:00\",\"dateModified\":\"2026-07-15T12:51:04+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#website\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/\",\"name\":\"AZUA AL INSTANTE\",\"description\":\"SIEMPRE DETR\\u00c1S DE LA NOTICIA!\",\"inLanguage\":\"es-DO\",\"publisher\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago - AZUA AL INSTANTE","description":"El director del Centro Cultural Palacio Consistorial, Rafaelito Mirabal, inform\u00f3 que los da\u00f1os ya fueron comunicados al Ministerio de Cultura, entidad responsable de la conservaci\u00f3n e intervenci\u00f3n de las edificaciones patrimoniales del pa\u00eds. El Palacio Consistorial de Santiago, uno de los principales centros culturales e hist\u00f3ricos de la Ciudad Coraz\u00f3n, presenta problemas de filtraciones, desprendimiento","canonical_url":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/#blogposting","name":"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago - AZUA AL INSTANTE","headline":"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago","author":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"publisher":{"@id":"https:\/\/azuaalinstante.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/azuaalinstante.com\/wp-content\/uploads\/2026\/07\/6a56e035319c5.jpeg","width":800,"height":600},"datePublished":"2026-07-15T12:50:39+00:00","dateModified":"2026-07-15T12:51:04+00:00","inLanguage":"es-DO","mainEntityOfPage":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/#webpage"},"isPartOf":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/#webpage"},"articleSection":"Rep\u00fablica"},{"@type":"BreadcrumbList","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com#listItem","position":1,"name":"Home","item":"https:\/\/azuaalinstante.com","nextItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/republica\/#listItem","name":"Rep\u00fablica"}},{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/republica\/#listItem","position":2,"name":"Rep\u00fablica","item":"https:\/\/azuaalinstante.com\/index.php\/category\/republica\/","nextItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/#listItem","name":"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago"},"previousItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/#listItem","position":3,"name":"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago","previousItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/republica\/#listItem","name":"Rep\u00fablica"}}]},{"@type":"Organization","@id":"https:\/\/azuaalinstante.com\/#organization","name":"AZUA AL INSTANTE","description":"SIEMPRE DETR\u00c1S DE LA NOTICIA!","url":"https:\/\/azuaalinstante.com\/"},{"@type":"Person","@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author","url":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/","name":"Redacci\u00f3n","image":{"@type":"ImageObject","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/d68b136e956cb2c839632b9025c3df5f0812f547e1ff3ca13ce11a5b13bf209c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Redacci\u00f3n"}},{"@type":"WebPage","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/#webpage","url":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/","name":"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago - AZUA AL INSTANTE","description":"El director del Centro Cultural Palacio Consistorial, Rafaelito Mirabal, inform\u00f3 que los da\u00f1os ya fueron comunicados al Ministerio de Cultura, entidad responsable de la conservaci\u00f3n e intervenci\u00f3n de las edificaciones patrimoniales del pa\u00eds. El Palacio Consistorial de Santiago, uno de los principales centros culturales e hist\u00f3ricos de la Ciudad Coraz\u00f3n, presenta problemas de filtraciones, desprendimiento","inLanguage":"es-DO","isPartOf":{"@id":"https:\/\/azuaalinstante.com\/#website"},"breadcrumb":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/#breadcrumblist"},"author":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"creator":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/azuaalinstante.com\/wp-content\/uploads\/2026\/07\/6a56e035319c5.jpeg","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/#mainImage","width":800,"height":600},"primaryImageOfPage":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/#mainImage"},"datePublished":"2026-07-15T12:50:39+00:00","dateModified":"2026-07-15T12:51:04+00:00"},{"@type":"WebSite","@id":"https:\/\/azuaalinstante.com\/#website","url":"https:\/\/azuaalinstante.com\/","name":"AZUA AL INSTANTE","description":"SIEMPRE DETR\u00c1S DE LA NOTICIA!","inLanguage":"es-DO","publisher":{"@id":"https:\/\/azuaalinstante.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"AZUA AL INSTANTE - SIEMPRE DETR\u00c1S DE LA NOTICIA!","og:type":"article","og:title":"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago - AZUA AL INSTANTE","og:description":"El director del Centro Cultural Palacio Consistorial, Rafaelito Mirabal, inform\u00f3 que los da\u00f1os ya fueron comunicados al Ministerio de Cultura, entidad responsable de la conservaci\u00f3n e intervenci\u00f3n de las edificaciones patrimoniales del pa\u00eds. El Palacio Consistorial de Santiago, uno de los principales centros culturales e hist\u00f3ricos de la Ciudad Coraz\u00f3n, presenta problemas de filtraciones, desprendimiento","og:url":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/","article:published_time":"2026-07-15T12:50:39+00:00","article:modified_time":"2026-07-15T12:51:04+00:00","twitter:card":"summary_large_image","twitter:title":"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago - AZUA AL INSTANTE","twitter:description":"El director del Centro Cultural Palacio Consistorial, Rafaelito Mirabal, inform\u00f3 que los da\u00f1os ya fueron comunicados al Ministerio de Cultura, entidad responsable de la conservaci\u00f3n e intervenci\u00f3n de las edificaciones patrimoniales del pa\u00eds. El Palacio Consistorial de Santiago, uno de los principales centros culturales e hist\u00f3ricos de la Ciudad Coraz\u00f3n, presenta problemas de filtraciones, desprendimiento"},"aioseo_meta_data":{"post_id":"12040","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-15 12:50:41","updated":"2026-07-15 15:30:51","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/azuaalinstante.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/azuaalinstante.com\/index.php\/category\/republica\/\" title=\"Rep\u00fablica\">Rep\u00fablica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFiltraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/azuaalinstante.com"},{"label":"Rep\u00fablica","link":"https:\/\/azuaalinstante.com\/index.php\/category\/republica\/"},{"label":"Filtraciones y desprendimiento del techo evidencian deterioro del Palacio Consistorial de Santiago","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/07\/15\/filtraciones-y-desprendimiento-del-techo-evidencian-deterioro-del-palacio-consistorial-de-santiago\/"}],"_links":{"self":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/12040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/comments?post=12040"}],"version-history":[{"count":1,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/12040\/revisions"}],"predecessor-version":[{"id":12042,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/12040\/revisions\/12042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media\/12041"}],"wp:attachment":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media?parent=12040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/categories?post=12040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/tags?post=12040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}