{"id":5686,"date":"2026-03-27T14:47:40","date_gmt":"2026-03-27T14:47:40","guid":{"rendered":"https:\/\/azuaalinstante.com\/?p=5686"},"modified":"2026-03-27T14:47:41","modified_gmt":"2026-03-27T14:47:41","slug":"christopher-sanchez-lanza-6-entradas-en-blanco-y-poncha-10-en-su-debut","status":"publish","type":"post","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/03\/27\/christopher-sanchez-lanza-6-entradas-en-blanco-y-poncha-10-en-su-debut\/","title":{"rendered":"Christopher S\u00e1nchez lanza 6 entradas en blanco y poncha 10 en su debut"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/vertical_main_image\/files\/fp\/uploads\/2026\/03\/26\/69c5d99d7e9b6.r_d.764-303.jpeg\" alt=\"Cristopher S\u00e1nchez, de los Filis, realiza un pitcheo durante su excelsa salida contra Texas en el primer juego de ambos clubes en la temporada.\"\/><figcaption class=\"wp-element-caption\">Cristopher S\u00e1nchez, de los Filis, realiza un pitcheo durante su excelsa salida contra Texas en el primer juego de ambos clubes en la temporada.ap<\/figcaption><\/figure>\n\n\n\n<p id=\"m3973-3972-3974\">Cristopher S\u00e1nchez ponch\u00f3 a 10 bateadores y permiti\u00f3 solo tres hits en seis entradas sin carreras en su primera apertura desde que firm\u00f3 una extensi\u00f3n de contrato de 104 millones de d\u00f3lares , y Kyle Schwarber y Alec Bohm conectaron jonrones cada uno para liderar a los Filis de Filadelfia a una victoria de 5-3 sobre los Rangers de Texas el jueves.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cristopher S\u00e1nchez ponch\u00f3 a 10 bateadores y permiti\u00f3 solo tres hits en seis entradas sin carreras en su primera apertura desde que firm\u00f3 una extensi\u00f3n de contrato de 104 millones de d\u00f3lares , y Kyle Schwarber y Alec Bohm conectaron jonrones cada uno para liderar a los Filis de Filadelfia a una victoria de 5-3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/5686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/comments?post=5686"}],"version-history":[{"count":1,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/5686\/revisions"}],"predecessor-version":[{"id":5688,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/5686\/revisions\/5688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media\/5687"}],"wp:attachment":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media?parent=5686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/categories?post=5686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/tags?post=5686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}