{"id":8486,"date":"2026-05-04T21:46:32","date_gmt":"2026-05-04T21:46:32","guid":{"rendered":"https:\/\/azuaalinstante.com\/?p=8486"},"modified":"2026-05-04T21:46:33","modified_gmt":"2026-05-04T21:46:33","slug":"multitud-protesta-contra-proyecto-minero-en-san-juan","status":"publish","type":"post","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/","title":{"rendered":"Multitud protesta contra proyecto minero en San Juan"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La marcha culmin\u00f3 en las inmediaciones de la Presa de Sabaneta, una de las obras m\u00e1s importante de San Juan. All\u00ed uniformados dispersaron la manifestaci\u00f3n con bombas lacrim\u00f3genas y agua a presi\u00f3n<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/vertical_main_image\/uploads\/2026\/05\/03\/69f815a133b96.jpeg\" alt=\"Los manifestantes llevaron carteles y pancartas con m\u00faltiples mensajes en contra del proyecto minero Romero en la Cordilla Central, cerca de la provincia sure\u00f1a de San Juan.\"\/><figcaption class=\"wp-element-caption\">Los manifestantes llevaron carteles y pancartas con m\u00faltiples mensajes en contra del proyecto minero Romero en la Cordilla Central, cerca de la provincia sure\u00f1a de San Juan.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo, RD<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m7110-7109-7111\">En defensa de los r\u00edos, gritando a una sola voz \u201cagua s\u00ed, oro no\u201d, el pueblo de San Juan sali\u00f3 a las calles el domingo y envi\u00f3 un mensaje contundente: no a la explotaci\u00f3n minera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La marcha culmin\u00f3 en las inmediaciones de la Presa de Sabaneta, una de las obras m\u00e1s importante de San Juan. All\u00ed uniformados dispersaron la manifestaci\u00f3n con bombas lacrim\u00f3genas y agua a presi\u00f3n Santo Domingo, RD En defensa de los r\u00edos, gritando a una sola voz \u201cagua s\u00ed, oro no\u201d, el pueblo de San Juan sali\u00f3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8488,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[25],"tags":[],"class_list":["post-8486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-region-sur"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La marcha culmin\u00f3 en las inmediaciones de la Presa de Sabaneta, una de las obras m\u00e1s importante de San Juan. All\u00ed uniformados dispersaron la manifestaci\u00f3n con bombas lacrim\u00f3genas y agua a presi\u00f3n Santo Domingo, RD En defensa de los r\u00edos, gritando a una sola voz \u201cagua s\u00ed, oro no\u201d, el pueblo de San Juan sali\u00f3\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Redacci\u00f3n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"AZUA AL INSTANTE - SIEMPRE DETR\u00c1S DE LA NOTICIA!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Multitud protesta contra proyecto minero en San Juan - AZUA AL INSTANTE\" \/>\n\t\t<meta property=\"og:description\" content=\"La marcha culmin\u00f3 en las inmediaciones de la Presa de Sabaneta, una de las obras m\u00e1s importante de San Juan. All\u00ed uniformados dispersaron la manifestaci\u00f3n con bombas lacrim\u00f3genas y agua a presi\u00f3n Santo Domingo, RD En defensa de los r\u00edos, gritando a una sola voz \u201cagua s\u00ed, oro no\u201d, el pueblo de San Juan sali\u00f3\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-05-04T21:46:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-04T21:46:33+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Multitud protesta contra proyecto minero en San Juan - AZUA AL INSTANTE\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La marcha culmin\u00f3 en las inmediaciones de la Presa de Sabaneta, una de las obras m\u00e1s importante de San Juan. All\u00ed uniformados dispersaron la manifestaci\u00f3n con bombas lacrim\u00f3genas y agua a presi\u00f3n Santo Domingo, RD En defensa de los r\u00edos, gritando a una sola voz \u201cagua s\u00ed, oro no\u201d, el pueblo de San Juan sali\u00f3\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/05\\\/04\\\/multitud-protesta-contra-proyecto-minero-en-san-juan\\\/#blogposting\",\"name\":\"Multitud protesta contra proyecto minero en San Juan - AZUA AL INSTANTE\",\"headline\":\"Multitud protesta contra proyecto minero en San Juan\",\"author\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/69f815a133b96.jpeg\",\"width\":800,\"height\":600},\"datePublished\":\"2026-05-04T21:46:32+00:00\",\"dateModified\":\"2026-05-04T21:46:33+00:00\",\"inLanguage\":\"es-DO\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/05\\\/04\\\/multitud-protesta-contra-proyecto-minero-en-san-juan\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/05\\\/04\\\/multitud-protesta-contra-proyecto-minero-en-san-juan\\\/#webpage\"},\"articleSection\":\"Regi\\u00f3n Sur\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/05\\\/04\\\/multitud-protesta-contra-proyecto-minero-en-san-juan\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/azuaalinstante.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/region-sur\\\/#listItem\",\"name\":\"Regi\\u00f3n Sur\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/region-sur\\\/#listItem\",\"position\":2,\"name\":\"Regi\\u00f3n Sur\",\"item\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/region-sur\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/05\\\/04\\\/multitud-protesta-contra-proyecto-minero-en-san-juan\\\/#listItem\",\"name\":\"Multitud protesta contra proyecto minero en San Juan\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/05\\\/04\\\/multitud-protesta-contra-proyecto-minero-en-san-juan\\\/#listItem\",\"position\":3,\"name\":\"Multitud protesta contra proyecto minero en San Juan\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/category\\\/region-sur\\\/#listItem\",\"name\":\"Regi\\u00f3n Sur\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\",\"name\":\"AZUA AL INSTANTE\",\"description\":\"SIEMPRE DETR\\u00c1S DE LA NOTICIA!\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/\",\"name\":\"Redacci\\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/05\\\/04\\\/multitud-protesta-contra-proyecto-minero-en-san-juan\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d68b136e956cb2c839632b9025c3df5f0812f547e1ff3ca13ce11a5b13bf209c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Redacci\\u00f3n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/05\\\/04\\\/multitud-protesta-contra-proyecto-minero-en-san-juan\\\/#webpage\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/05\\\/04\\\/multitud-protesta-contra-proyecto-minero-en-san-juan\\\/\",\"name\":\"Multitud protesta contra proyecto minero en San Juan - AZUA AL INSTANTE\",\"description\":\"La marcha culmin\\u00f3 en las inmediaciones de la Presa de Sabaneta, una de las obras m\\u00e1s importante de San Juan. All\\u00ed uniformados dispersaron la manifestaci\\u00f3n con bombas lacrim\\u00f3genas y agua a presi\\u00f3n Santo Domingo, RD En defensa de los r\\u00edos, gritando a una sola voz \\u201cagua s\\u00ed, oro no\\u201d, el pueblo de San Juan sali\\u00f3\",\"inLanguage\":\"es-DO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/05\\\/04\\\/multitud-protesta-contra-proyecto-minero-en-san-juan\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/author\\\/redaccion\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/69f815a133b96.jpeg\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/05\\\/04\\\/multitud-protesta-contra-proyecto-minero-en-san-juan\\\/#mainImage\",\"width\":800,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/index.php\\\/2026\\\/05\\\/04\\\/multitud-protesta-contra-proyecto-minero-en-san-juan\\\/#mainImage\"},\"datePublished\":\"2026-05-04T21:46:32+00:00\",\"dateModified\":\"2026-05-04T21:46:33+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#website\",\"url\":\"https:\\\/\\\/azuaalinstante.com\\\/\",\"name\":\"AZUA AL INSTANTE\",\"description\":\"SIEMPRE DETR\\u00c1S DE LA NOTICIA!\",\"inLanguage\":\"es-DO\",\"publisher\":{\"@id\":\"https:\\\/\\\/azuaalinstante.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Multitud protesta contra proyecto minero en San Juan - AZUA AL INSTANTE","description":"La marcha culmin\u00f3 en las inmediaciones de la Presa de Sabaneta, una de las obras m\u00e1s importante de San Juan. All\u00ed uniformados dispersaron la manifestaci\u00f3n con bombas lacrim\u00f3genas y agua a presi\u00f3n Santo Domingo, RD En defensa de los r\u00edos, gritando a una sola voz \u201cagua s\u00ed, oro no\u201d, el pueblo de San Juan sali\u00f3","canonical_url":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/#blogposting","name":"Multitud protesta contra proyecto minero en San Juan - AZUA AL INSTANTE","headline":"Multitud protesta contra proyecto minero en San Juan","author":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"publisher":{"@id":"https:\/\/azuaalinstante.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/azuaalinstante.com\/wp-content\/uploads\/2026\/05\/69f815a133b96.jpeg","width":800,"height":600},"datePublished":"2026-05-04T21:46:32+00:00","dateModified":"2026-05-04T21:46:33+00:00","inLanguage":"es-DO","mainEntityOfPage":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/#webpage"},"isPartOf":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/#webpage"},"articleSection":"Regi\u00f3n Sur"},{"@type":"BreadcrumbList","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com#listItem","position":1,"name":"Home","item":"https:\/\/azuaalinstante.com","nextItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/region-sur\/#listItem","name":"Regi\u00f3n Sur"}},{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/region-sur\/#listItem","position":2,"name":"Regi\u00f3n Sur","item":"https:\/\/azuaalinstante.com\/index.php\/category\/region-sur\/","nextItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/#listItem","name":"Multitud protesta contra proyecto minero en San Juan"},"previousItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/#listItem","position":3,"name":"Multitud protesta contra proyecto minero en San Juan","previousItem":{"@type":"ListItem","@id":"https:\/\/azuaalinstante.com\/index.php\/category\/region-sur\/#listItem","name":"Regi\u00f3n Sur"}}]},{"@type":"Organization","@id":"https:\/\/azuaalinstante.com\/#organization","name":"AZUA AL INSTANTE","description":"SIEMPRE DETR\u00c1S DE LA NOTICIA!","url":"https:\/\/azuaalinstante.com\/"},{"@type":"Person","@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author","url":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/","name":"Redacci\u00f3n","image":{"@type":"ImageObject","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/d68b136e956cb2c839632b9025c3df5f0812f547e1ff3ca13ce11a5b13bf209c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Redacci\u00f3n"}},{"@type":"WebPage","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/#webpage","url":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/","name":"Multitud protesta contra proyecto minero en San Juan - AZUA AL INSTANTE","description":"La marcha culmin\u00f3 en las inmediaciones de la Presa de Sabaneta, una de las obras m\u00e1s importante de San Juan. All\u00ed uniformados dispersaron la manifestaci\u00f3n con bombas lacrim\u00f3genas y agua a presi\u00f3n Santo Domingo, RD En defensa de los r\u00edos, gritando a una sola voz \u201cagua s\u00ed, oro no\u201d, el pueblo de San Juan sali\u00f3","inLanguage":"es-DO","isPartOf":{"@id":"https:\/\/azuaalinstante.com\/#website"},"breadcrumb":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/#breadcrumblist"},"author":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"creator":{"@id":"https:\/\/azuaalinstante.com\/index.php\/author\/redaccion\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/azuaalinstante.com\/wp-content\/uploads\/2026\/05\/69f815a133b96.jpeg","@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/#mainImage","width":800,"height":600},"primaryImageOfPage":{"@id":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/#mainImage"},"datePublished":"2026-05-04T21:46:32+00:00","dateModified":"2026-05-04T21:46:33+00:00"},{"@type":"WebSite","@id":"https:\/\/azuaalinstante.com\/#website","url":"https:\/\/azuaalinstante.com\/","name":"AZUA AL INSTANTE","description":"SIEMPRE DETR\u00c1S DE LA NOTICIA!","inLanguage":"es-DO","publisher":{"@id":"https:\/\/azuaalinstante.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"AZUA AL INSTANTE - SIEMPRE DETR\u00c1S DE LA NOTICIA!","og:type":"article","og:title":"Multitud protesta contra proyecto minero en San Juan - AZUA AL INSTANTE","og:description":"La marcha culmin\u00f3 en las inmediaciones de la Presa de Sabaneta, una de las obras m\u00e1s importante de San Juan. All\u00ed uniformados dispersaron la manifestaci\u00f3n con bombas lacrim\u00f3genas y agua a presi\u00f3n Santo Domingo, RD En defensa de los r\u00edos, gritando a una sola voz \u201cagua s\u00ed, oro no\u201d, el pueblo de San Juan sali\u00f3","og:url":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/","article:published_time":"2026-05-04T21:46:32+00:00","article:modified_time":"2026-05-04T21:46:33+00:00","twitter:card":"summary_large_image","twitter:title":"Multitud protesta contra proyecto minero en San Juan - AZUA AL INSTANTE","twitter:description":"La marcha culmin\u00f3 en las inmediaciones de la Presa de Sabaneta, una de las obras m\u00e1s importante de San Juan. All\u00ed uniformados dispersaron la manifestaci\u00f3n con bombas lacrim\u00f3genas y agua a presi\u00f3n Santo Domingo, RD En defensa de los r\u00edos, gritando a una sola voz \u201cagua s\u00ed, oro no\u201d, el pueblo de San Juan sali\u00f3"},"aioseo_meta_data":{"post_id":"8486","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-05-04 21:46:33","updated":"2026-05-04 21:59:44","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/azuaalinstante.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/azuaalinstante.com\/index.php\/category\/region-sur\/\" title=\"Regi\u00f3n Sur\">Regi\u00f3n Sur<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMultitud protesta contra proyecto minero en San Juan\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/azuaalinstante.com"},{"label":"Regi\u00f3n Sur","link":"https:\/\/azuaalinstante.com\/index.php\/category\/region-sur\/"},{"label":"Multitud protesta contra proyecto minero en San Juan","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/04\/multitud-protesta-contra-proyecto-minero-en-san-juan\/"}],"_links":{"self":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/comments?post=8486"}],"version-history":[{"count":1,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8486\/revisions"}],"predecessor-version":[{"id":8489,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8486\/revisions\/8489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media\/8488"}],"wp:attachment":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media?parent=8486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/categories?post=8486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/tags?post=8486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}