{"id":8852,"date":"2026-05-12T23:45:38","date_gmt":"2026-05-12T23:45:38","guid":{"rendered":"https:\/\/azuaalinstante.com\/?p=8852"},"modified":"2026-05-12T23:45:39","modified_gmt":"2026-05-12T23:45:39","slug":"discusion-entre-joseph-caceres-y-jesus-nova-casi-termina-en-golpes-durante-programa-de-television","status":"publish","type":"post","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/12\/discusion-entre-joseph-caceres-y-jesus-nova-casi-termina-en-golpes-durante-programa-de-television\/","title":{"rendered":"Discusi\u00f3n entre Joseph C\u00e1ceres y Jes\u00fas Nova casi termina en golpes durante programa de televisi\u00f3n"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">En el video, se escucha al cronista de arte amenazar con darle \"un tiro\" a Jes\u00fas Nova<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/vertical_main_image\/uploads\/2026\/05\/12\/6a035fcbed7c3.jpeg\" alt=\"Jes\u00fas Nova y Joseph C\u00e1ceres.\"\/><figcaption class=\"wp-element-caption\">Jes\u00fas Nova y Joseph C\u00e1ceres.<\/figcaption><\/figure>\n\n\n\n<p id=\"m80371-80370-80372\">Los periodistas&nbsp;<strong>Joseph C\u00e1ceres<\/strong>&nbsp;y&nbsp;<strong>Jes\u00fas Nova<\/strong>&nbsp;terminaron casi a golpes una discusi\u00f3n durante la grabaci\u00f3n de un programa de televisi\u00f3n especial con motivo a la celebraci\u00f3n de los 37 a\u00f1os de carrera de la artista&nbsp;<strong>Chabelly y su Orquesta<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el video, se escucha al cronista de arte amenazar con darle \"un tiro\" a Jes\u00fas Nova Los periodistas&nbsp;Joseph C\u00e1ceres&nbsp;y&nbsp;Jes\u00fas Nova&nbsp;terminaron casi a golpes una discusi\u00f3n durante la grabaci\u00f3n de un programa de televisi\u00f3n especial con motivo a la celebraci\u00f3n de los 37 a\u00f1os de carrera de la artista&nbsp;Chabelly y su Orquesta.<\/p>\n","protected":false},"author":2,"featured_media":8853,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-8852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/comments?post=8852"}],"version-history":[{"count":1,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8852\/revisions"}],"predecessor-version":[{"id":8854,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8852\/revisions\/8854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media\/8853"}],"wp:attachment":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media?parent=8852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/categories?post=8852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/tags?post=8852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}