{"id":8886,"date":"2026-05-13T10:14:54","date_gmt":"2026-05-13T10:14:54","guid":{"rendered":"https:\/\/azuaalinstante.com\/?p=8886"},"modified":"2026-05-13T10:14:55","modified_gmt":"2026-05-13T10:14:55","slug":"ministro-de-salud-victor-atallah-anuncia-nombramiento-de-1115-enfermeras","status":"publish","type":"post","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/13\/ministro-de-salud-victor-atallah-anuncia-nombramiento-de-1115-enfermeras\/","title":{"rendered":"Ministro de Salud V\u00edctor Atallah anuncia nombramiento de 1,115 enfermeras"},"content":{"rendered":"\n<p><em>Este 12 de mayo se conmemora el D\u00eda Internacional de la Enfermer\u00eda<\/em><\/p>\n\n\n\n<p><em>Santo Domingo, R.D. \u2013<\/em> El ministro de Salud, V\u00edctor Atallah, anunci\u00f3 este martes el nombramiento fijo de 1,115 enfermeras que permanec\u00edan contratadas desde hace aproximadamente cuatro a\u00f1os, incluyendo personal incorporado durante la pandemia del COVID-19, como parte de los acuerdos y el proceso de di\u00e1logo sostenido con el sector salud.<\/p>\n\n\n\n<p>Al encabezar una misa oficiada en la Catedral Primada de Am\u00e9rica, con motivo de la conmemoraci\u00f3n del D\u00eda Internacional de la Enfermer\u00eda, Atallah explic\u00f3 que esta disposici\u00f3n busca eliminar la figura de enfermeras jornaleras dentro del sistema sanitario y responder a una demanda que el gremio ven\u00eda planteando desde hace varios a\u00f1os.<\/p>\n\n\n\n<p>El funcionario destac\u00f3 que esta medida no solo garantiza estabilidad laboral, sino tambi\u00e9n mejores condiciones para el personal beneficiado.<\/p>\n\n\n\n<p>\u201cEsto no solamente les da la calidad de un puesto fijo, tambi\u00e9n les garantiza servicios, seguro y un incremento en sus ingresos de alrededor de un 30 % anual, adem\u00e1s de la posibilidad de seguir avanzando dentro del sistema\u201d, expres\u00f3.<\/p>\n\n\n\n<p>El ministro sostuvo que el Gobierno mantiene una pol\u00edtica de di\u00e1logo abierto con los diferentes sectores y asegur\u00f3 que las conversaciones con el personal de salud contin\u00faan avanzando con acciones concretas.<\/p>\n\n\n\n<p>\u201cMe acabo de comprometer p\u00fablicamente a fijar 1,115 enfermeras. No m\u00e1s enfermeras jornaleras. Estamos cumpliendo con cada uno de los compromisos asumidos\u201d, manifest\u00f3.<\/p>\n\n\n\n<p>Por su parte, el director del Servicio Nacional de Salud (SNS), Julio Landr\u00f3n, inform\u00f3 que en lo que resta del a\u00f1o el Gobierno habilitar\u00e1 unas 450 plazas de enfermer\u00eda y m\u00e1s de 300 reclasificaciones para beneficiar al sector, cuyos representantes agradecieron las acciones impulsadas a favor del personal.<\/p>\n\n\n\n<p>La directora Nacional de Enfermer\u00eda, Yolanda Saturria, resalt\u00f3 la labor que realiza el personal de enfermer\u00eda, al considerar que desempe\u00f1a una funci\u00f3n loable y significativa para proteger la salud de la poblaci\u00f3n.<\/p>\n\n\n\n<p>A la misa, celebrada en la Catedral Primada de Am\u00e9rica y presidida por el padre Cecilid de los Santos, asistieron la primera dama de la Rep\u00fablica, Raquel Arbaje; el director del Servicio Regional de Salud Metropolitano, Edison F\u00e9lix F\u00e9lix, adem\u00e1s de otras autoridades e invitados especiales.<\/p>\n\n\n\n<p><em>Situaci\u00f3n del norovirus y hantavirus<\/em><\/p>\n\n\n\n<p>En otro orden, el titular de Salud inform\u00f3 que el pa\u00eds mantiene vigilancia epidemiol\u00f3gica activa ante enfermedades virales, siguiendo las recomendaciones de la Organizaci\u00f3n Mundial de la Salud.<\/p>\n\n\n\n<p>Asegur\u00f3 que actualmente en el pa\u00eds no hay brotes de norovirus y explic\u00f3 que, no es una enfermedad nueva ni desconocida y que, aunque suelen registrarse casos espor\u00e1dicos, se trata de una enfermedad viral com\u00fan asociada a cuadros gastrointestinales caracterizados por v\u00f3mitos y diarrea, por lo que no debe generar alarma en la poblaci\u00f3n.<\/p>\n\n\n\n<p>Asegur\u00f3 que nunca hubo riesgo para el pa\u00eds por la llegada del barco y que se tomaron todas las medidas sanitarias correspondientes.<\/p>\n\n\n\n<p>Asimismo, reiter\u00f3 que el pa\u00eds se mantiene vigilante ante cualquier evento epidemiol\u00f3gico internacional, incluyendo los casos de hantavirus reportados en otros territorios, al tiempo que aclar\u00f3 que se trata de un virus totalmente diferente al norovirus y que actualmente no existe presencia de esa enfermedad en Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p>Indic\u00f3 que las autoridades sanitarias contin\u00faan fortaleciendo la preparaci\u00f3n del personal m\u00e9dico, as\u00ed como los protocolos de vigilancia y respuesta, con el objetivo de garantizar una detecci\u00f3n oportuna ante cualquier eventualidad.<\/p>\n\n\n\n<p>\u201cNo tenemos casos de hantavirus en el pa\u00eds, pero mantenemos una vigilancia permanente y la capacitaci\u00f3n continua del personal de salud, como parte de las medidas preventivas\u201d, expres\u00f3.<\/p>\n\n\n\n<p><em>Direcci\u00f3n de Comunicaciones 12 de mayo de 2026.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este 12 de mayo se conmemora el D\u00eda Internacional de la Enfermer\u00eda Santo Domingo, R.D. \u2013 El ministro de Salud, V\u00edctor Atallah, anunci\u00f3 este martes el nombramiento fijo de 1,115 enfermeras que permanec\u00edan contratadas desde hace aproximadamente cuatro a\u00f1os, incluyendo personal incorporado durante la pandemia del COVID-19, como parte de los acuerdos y el proceso [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8887,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-8886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-republica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/comments?post=8886"}],"version-history":[{"count":1,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8886\/revisions"}],"predecessor-version":[{"id":8888,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8886\/revisions\/8888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media\/8887"}],"wp:attachment":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media?parent=8886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/categories?post=8886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/tags?post=8886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}