{"id":8940,"date":"2026-05-13T12:18:03","date_gmt":"2026-05-13T12:18:03","guid":{"rendered":"https:\/\/azuaalinstante.com\/?p=8940"},"modified":"2026-05-13T12:18:04","modified_gmt":"2026-05-13T12:18:04","slug":"banco-central-aplaza-para-enero-2027-retorno-de-facilidades-de-liquidez","status":"publish","type":"post","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/13\/banco-central-aplaza-para-enero-2027-retorno-de-facilidades-de-liquidez\/","title":{"rendered":"Banco Central aplaza para enero 2027 retorno de facilidades de liquidez"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El gobernador H\u00e9ctor Valdez Albizu indic\u00f3 dijo que la inflaci\u00f3n interanual podr\u00eda ubicarse por encima del rango objetivo de 4 % \u00b1 1 %, hasta el cierre del a\u00f1o.<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/vertical_main_image\/uploads\/2026\/04\/26\/69eea291486f5.jpeg\" alt=\"El Banco Central en una reciente publicaci\u00f3n, as\u00ed como la CEPAL y ahora el FMI, bajan la tasa de crecimiento y la proyectan en un centrado 3.5%.\"\/><figcaption class=\"wp-element-caption\">La instituci\u00f3n se mantendr\u00e1 monitoreando el potencial impacto de la guerra en Medio Oriente  ARCHIVO<\/figcaption><\/figure>\n\n\n\n<p id=\"m102153-102152-102154\">El Banco Central decidi\u00f3 aplazar hasta enero del pr\u00f3ximo a\u00f1o, el retorno de unos RD$46 mil millones de facilidades de liquidez, que estaban previstos para reintegrarse a partir de junio del presente a\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador H\u00e9ctor Valdez Albizu indic\u00f3 dijo que la inflaci\u00f3n interanual podr\u00eda ubicarse por encima del rango objetivo de 4 % \u00b1 1 %, hasta el cierre del a\u00f1o. El Banco Central decidi\u00f3 aplazar hasta enero del pr\u00f3ximo a\u00f1o, el retorno de unos RD$46 mil millones de facilidades de liquidez, que estaban previstos para reintegrarse [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8941,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-8940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/comments?post=8940"}],"version-history":[{"count":1,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8940\/revisions"}],"predecessor-version":[{"id":8942,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8940\/revisions\/8942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media\/8941"}],"wp:attachment":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media?parent=8940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/categories?post=8940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/tags?post=8940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}