{"id":8962,"date":"2026-05-13T19:33:19","date_gmt":"2026-05-13T19:33:19","guid":{"rendered":"https:\/\/azuaalinstante.com\/?p=8962"},"modified":"2026-05-13T19:33:20","modified_gmt":"2026-05-13T19:33:20","slug":"celinee-santos-rompe-record-en-la-casa-de-los-famosos-tras-ser-salvada-por-el-publico-ocho-veces","status":"publish","type":"post","link":"https:\/\/azuaalinstante.com\/index.php\/2026\/05\/13\/celinee-santos-rompe-record-en-la-casa-de-los-famosos-tras-ser-salvada-por-el-publico-ocho-veces\/","title":{"rendered":"Celinee Santos rompe r\u00e9cord en \"La casa de los famosos\" tras ser salvada por el p\u00fablico ocho veces"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La ganadora de la cuarta temporada del reality de Telemundo, la actriz boricua Maripily Rivera, ostentaba el r\u00e9cord anterior con siete regresos del SUM (sala de eliminaci\u00f3n).<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/listindiario.com\/files\/vertical_main_image\/uploads\/2026\/05\/13\/6a04bb9d1e566.jpeg\" alt=\"Celinee Santos, Miss Universo Rep\u00fablica Dominicana 2024.\"\/><figcaption class=\"wp-element-caption\">Celinee Santos, Miss Universo Rep\u00fablica Dominicana 2024.Foto: Instagram<\/figcaption><\/figure>\n\n\n\n<p id=\"m18736-18735-18737\"><strong>Celinee Santos&nbsp;<\/strong>est\u00e1 a punto de llegar a la final de&nbsp;<strong>\"La casa de los famosos 6&#8243;<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ganadora de la cuarta temporada del reality de Telemundo, la actriz boricua Maripily Rivera, ostentaba el r\u00e9cord anterior con siete regresos del SUM (sala de eliminaci\u00f3n). Celinee Santos&nbsp;est\u00e1 a punto de llegar a la final de&nbsp;\"La casa de los famosos 6&#8243;.<\/p>\n","protected":false},"author":2,"featured_media":8963,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-8962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/comments?post=8962"}],"version-history":[{"count":1,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8962\/revisions"}],"predecessor-version":[{"id":8964,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/posts\/8962\/revisions\/8964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media\/8963"}],"wp:attachment":[{"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/media?parent=8962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/categories?post=8962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azuaalinstante.com\/index.php\/wp-json\/wp\/v2\/tags?post=8962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}